{"id":33,"date":"2023-11-27T09:11:26","date_gmt":"2023-11-27T09:11:26","guid":{"rendered":"https:\/\/demo.bravisthemes.com\/graviton\/?page_id=33"},"modified":"2026-07-06T15:44:50","modified_gmt":"2026-07-06T12:44:50","slug":"our-projects","status":"publish","type":"page","link":"https:\/\/mk-mykonos.gr\/el\/our-projects\/","title":{"rendered":"\u03a4\u03b1 \u03ad\u03c1\u03b3\u03b1 \u03bc\u03b1\u03c2"},"content":{"rendered":"<div data-elementor-type=\"wp-page\" data-elementor-id=\"33\" class=\"elementor elementor-33\" data-elementor-post-type=\"page\">\n\t\t\t\t        <section class=\"elementor-section elementor-top-section elementor-element elementor-element-e8fa269 elementor-section-full_width elementor-section-stretched pxl-full-content-with-space-start elementor-section-height-default elementor-section-height-default pxl-row-scroll-none pxl-zoom-point-false pxl-section-overflow-visible pxl-section-fix-none pxl-bg-color-none pxl-section-overlay-none\" data-id=\"e8fa269\" data-element_type=\"section\" data-e-type=\"section\" data-settings=\"{&quot;stretch_section&quot;:&quot;section-stretched&quot;,&quot;background_background&quot;:&quot;classic&quot;}\" style=\"padding-left: calc( (100% - 1650px)\/2);\">\n\n                \n                <div class=\"elementor-container elementor-column-gap-extended\">\n                <div class=\"elementor-column elementor-col-50 elementor-top-column elementor-element elementor-element-706a9d8 pxl-column-none pxl-column-overflow-hidden-no\" data-id=\"706a9d8\" data-element_type=\"column\" data-e-type=\"column\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\r\n        <div class=\"elementor-widget-wrap elementor-element-populated\">\r\n                     \r\n        \t\t<div class=\"elementor-element elementor-element-49a80ba elementor-widget elementor-widget-pxl_heading\" data-id=\"49a80ba\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"pxl_heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\n<div id=\"pxl-pxl_heading-49a80ba-7101\" class=\"pxl-heading px-sub-title-default-style\">\n\t<div class=\"pxl-heading--inner\">\n\t\t\t\t\t<div class=\"pxl-item--subtitle px-sub-title-default\" data-wow-delay=\"ms\">\n\t\t\t\t<span class=\"pxl-item--subtext\">\n\t\t\t\t\t\t\t\t\t\t\u0395\u03be\u03b5\u03c1\u03b5\u03c5\u03bd\u03ae\u03c3\u03c4\u03b5 \u03c4\u03b7 \u03b4\u03bf\u03c5\u03bb\u03b5\u03b9\u03ac \u03bc\u03b1\u03c2\t\t\t\t<\/span>\n\t\t\t<\/div>\n\t\t\n\t\t\t<h1 class=\"pxl-item--title style-default highlight-default\" data-wow-delay=\"ms\">\n\t\t\t\t\t\t\t\u03a4\u03b1 \u03ad\u03c1\u03b3\u03b1 \u03bc\u03b1\u03c2\t\n\t\t\t\t\n\t\t<\/h1>\n\t<\/div>\n<\/div> \t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-52fc5cd elementor-widget elementor-widget-pxl_text_editor\" data-id=\"52fc5cd\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"pxl_text_editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"pxl-text-editor\">\n\t<div class=\"pxl-item--inner\" data-wow-delay=\"ms\">\n\t\t<p>\u0397 \u03b3\u03ba\u03b1\u03bb\u03b5\u03c1\u03af \u03bc\u03b1\u03c2 \u03b1\u03bd\u03b1\u03b4\u03b5\u03b9\u03ba\u03bd\u03cd\u03b5\u03b9 \u03c4\u03b7\u03bd \u03b1\u03c6\u03bf\u03c3\u03af\u03c9\u03c3\u03b7, \u03c4\u03b7 \u03b4\u03b7\u03bc\u03b9\u03bf\u03c5\u03c1\u03b3\u03b9\u03ba\u03cc\u03c4\u03b7\u03c4\u03b1 \u03ba\u03b1\u03b9 \u03c4\u03b7\u03bd \u03c4\u03b5\u03c7\u03bd\u03b9\u03ba\u03ae \u03b1\u03c1\u03c4\u03b9\u03cc\u03c4\u03b7\u03c4\u03b1 \u03c0\u03bf\u03c5 \u03b5\u03c0\u03b5\u03bd\u03b4\u03cd\u03bf\u03c5\u03bc\u03b5 \u03c3\u03b5 \u03ba\u03ac\u03b8\u03b5 \u03ad\u03c1\u03b3\u03bf.<\/p>\t\t\n\t<\/div>\n<\/div>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-92de091 elementor-widget__width-initial elementor-widget elementor-widget-pxl_breadcrumb\" data-id=\"92de091\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"pxl_breadcrumb.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"pxl-breadcrumb-wrap\">\n\t<ul class=\"pxl-breadcrumb\"><li><span class=\"breadcrumb-entry\">\u0391\u03c1\u03c7\u03b9\u03ba\u03ae \u03c3\u03b5\u03bb\u03af\u03b4\u03b1<\/span><\/li><\/ul><\/div>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t            <\/div>\r\n        <\/div>\r\n                <div class=\"elementor-column elementor-col-50 elementor-top-column elementor-element elementor-element-5bcf8d3 pxl-column-none pxl-column-overflow-hidden-no\" data-id=\"5bcf8d3\" data-element_type=\"column\" data-e-type=\"column\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\r\n        <div class=\"elementor-widget-wrap elementor-element-populated\">\r\n                     \r\n        \t\t<div class=\"elementor-element elementor-element-91cd94b elementor-widget elementor-widget-spacer\" data-id=\"91cd94b\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"spacer.default\">\n\t\t\t\t\t\t\t<div class=\"elementor-spacer\">\n\t\t\t<div class=\"elementor-spacer-inner\"><\/div>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t            <\/div>\r\n        <\/div>\r\n        \t\t\t<\/div>\n\t\t<\/section>\n\t\t        <section class=\"elementor-section elementor-top-section elementor-element elementor-element-c4c93c9 pxl-section-overflow-hidden elementor-section-boxed elementor-section-height-default elementor-section-height-default pxl-row-scroll-none pxl-zoom-point-false pxl-section-fix-none pxl-bg-color-none pxl-section-overlay-none\" data-id=\"c4c93c9\" data-element_type=\"section\" data-e-type=\"section\">\n\n                \n                <div class=\"elementor-container elementor-column-gap-default\">\n                <div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-6849cd4 pxl-column-none pxl-column-overflow-hidden-no\" data-id=\"6849cd4\" data-element_type=\"column\" data-e-type=\"column\">\r\n        <div class=\"elementor-widget-wrap elementor-element-populated\">\r\n                     \r\n        \t\t<div class=\"elementor-element elementor-element-533f488 elementor-widget elementor-widget-pxl_fillter_showcase\" data-id=\"533f488\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"pxl_fillter_showcase.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\n<div class=\"pxl-grid pxl-showcase-grid pxl-showcase-grid1 pxl-showcase-layout1\">\n            <div class=\"pxl-grid-filter normal style-1\">\n            <div class=\"pxl--filter-inner\">\n                <span class=\"filter-item active\" data-filter=\"*\">\u038c\u03bb\u03b1<\/span>\n                                    <span class=\"filter-item\" data-filter=\".Projects\">\n                        \u0388\u03c1\u03b3\u03b1                    <\/span>\n                                    <span class=\"filter-item\" data-filter=\".Panormos-House\">\n                        \u039a\u03b1\u03c4\u03bf\u03b9\u03ba\u03af\u03b1 \u00ab\u03a0\u03b1\u03bd\u03bf\u03c1\u03bc\u03cc\u03c2\u00bb                    <\/span>\n                                    <span class=\"filter-item\" data-filter=\".Korfos-House\">\n                        \u039a\u03b1\u03c4\u03bf\u03b9\u03ba\u03af\u03b1 \u00ab\u039a\u03cc\u03c1\u03c6\u03bf\u03c2\u00bb                    <\/span>\n                                    <span class=\"filter-item\" data-filter=\".Villa-in-Mykonos\">\n                        \u0392\u03af\u03bb\u03b1 \u03c3\u03c4\u03b7 \u039c\u03cd\u03ba\u03bf\u03bd\u03bf                    <\/span>\n                                    <span class=\"filter-item\" data-filter=\".54-Bar\">\n                        54 Bar                    <\/span>\n                                    <span class=\"filter-item\" data-filter=\".Bowling\">\n                        \u039c\u03c0\u03cc\u03bf\u03c5\u03bb\u03b9\u03bd\u03b3\u03ba                    <\/span>\n                                    <span class=\"filter-item\" data-filter=\".Palladium\">\n                        Palladium                    <\/span>\n                                    <span class=\"filter-item\" data-filter=\".Saint-John-Hotel\">\n                        \u039e\u03b5\u03bd\u03bf\u03b4\u03bf\u03c7\u03b5\u03af\u03bf Saint John                    <\/span>\n                                    <span class=\"filter-item\" data-filter=\".Vicolo\">\n                        Vicolo                    <\/span>\n                            <\/div>\n        <\/div>\n        <div class=\"pxl-el-divider visible\"><\/div>\n        <div class=\"pxl-grid-inner pxl-grid-masonry row\" data-gutter=\"15\" data-layout=\"Array\">\n        <div class=\"grid-sizer col-xl-4 col-lg-4 col-md-6 col-sm-6 col-12\"><\/div>\n                    <div class=\"pxl-grid-item col-xl-4 col-lg-4 col-md-6 col-sm-6 col-12 Projects\">\n                <div class=\"pxl-item--inner\">\n                                            <div class=\"pxl-item--image\">\n                            <img fetchpriority=\"high\" decoding=\"async\" width=\"1920\" height=\"2560\" src=\"https:\/\/mk-mykonos.gr\/wp-content\/uploads\/2025\/10\/20230213_183709.webp\" class=\"no-lazyload\" alt=\"PROJECT MK MYKONOS ENGINEERS\" \/>                            <a href=\"https:\/\/mk-mykonos.gr\/wp-content\/uploads\/2025\/10\/20230213_183709.webp\" class=\"show\"><i class=\"fas fa-eye\"><\/i><\/a>\n                        <\/div>\n                                    <\/div>\n            <\/div>\n                    <div class=\"pxl-grid-item col-xl-4 col-lg-4 col-md-6 col-sm-6 col-12 Projects\">\n                <div class=\"pxl-item--inner\">\n                                            <div class=\"pxl-item--image\">\n                            <img decoding=\"async\" width=\"1920\" height=\"1440\" src=\"https:\/\/mk-mykonos.gr\/wp-content\/uploads\/2025\/10\/20230220_125322.webp\" class=\"no-lazyload\" alt=\"PROJECT MK MYKONOS ENGINEERS\" \/>                            <a href=\"https:\/\/mk-mykonos.gr\/wp-content\/uploads\/2025\/10\/20230220_125322.webp\" class=\"show\"><i class=\"fas fa-eye\"><\/i><\/a>\n                        <\/div>\n                                    <\/div>\n            <\/div>\n                    <div class=\"pxl-grid-item col-xl-4 col-lg-4 col-md-6 col-sm-6 col-12 Projects\">\n                <div class=\"pxl-item--inner\">\n                                            <div class=\"pxl-item--image\">\n                            <img decoding=\"async\" width=\"1920\" height=\"2560\" src=\"https:\/\/mk-mykonos.gr\/wp-content\/uploads\/2025\/10\/20230224_114108.webp\" class=\"no-lazyload\" alt=\"PROJECT MK MYKONOS ENGINEERS\" \/>                            <a href=\"https:\/\/mk-mykonos.gr\/wp-content\/uploads\/2025\/10\/20230224_114108.webp\" class=\"show\"><i class=\"fas fa-eye\"><\/i><\/a>\n                        <\/div>\n                                    <\/div>\n            <\/div>\n                    <div class=\"pxl-grid-item col-xl-6 col-lg-6 col-md-6 col-sm-6 col-12 Projects\">\n                <div class=\"pxl-item--inner\">\n                                            <div class=\"pxl-item--image\">\n                            <img loading=\"lazy\" decoding=\"async\" width=\"1920\" height=\"1440\" src=\"https:\/\/mk-mykonos.gr\/wp-content\/uploads\/2025\/10\/20230301_131923.webp\" class=\"no-lazyload\" alt=\"PROJECT MK MYKONOS ENGINEERS\" \/>                            <a href=\"https:\/\/mk-mykonos.gr\/wp-content\/uploads\/2025\/10\/20230301_131923.webp\" class=\"show\"><i class=\"fas fa-eye\"><\/i><\/a>\n                        <\/div>\n                                    <\/div>\n            <\/div>\n                    <div class=\"pxl-grid-item col-xl-6 col-lg-6 col-md-6 col-sm-6 col-12 Projects\">\n                <div class=\"pxl-item--inner\">\n                                            <div class=\"pxl-item--image\">\n                            <img loading=\"lazy\" decoding=\"async\" width=\"1920\" height=\"1440\" src=\"https:\/\/mk-mykonos.gr\/wp-content\/uploads\/2025\/10\/20230328_114439.webp\" class=\"no-lazyload\" alt=\"PROJECT MK MYKONOS ENGINEERS\" \/>                            <a href=\"https:\/\/mk-mykonos.gr\/wp-content\/uploads\/2025\/10\/20230328_114439.webp\" class=\"show\"><i class=\"fas fa-eye\"><\/i><\/a>\n                        <\/div>\n                                    <\/div>\n            <\/div>\n                    <div class=\"pxl-grid-item col-xl-12 col-lg-12 col-md-12 col-sm-12 col-12 Projects\">\n                <div class=\"pxl-item--inner\">\n                                            <div class=\"pxl-item--image\">\n                            <img loading=\"lazy\" decoding=\"async\" width=\"1920\" height=\"1440\" src=\"https:\/\/mk-mykonos.gr\/wp-content\/uploads\/2025\/10\/20230330_143735.webp\" class=\"no-lazyload\" alt=\"PROJECT MK MYKONOS ENGINEERS\" \/>                            <a href=\"https:\/\/mk-mykonos.gr\/wp-content\/uploads\/2025\/10\/20230330_143735.webp\" class=\"show\"><i class=\"fas fa-eye\"><\/i><\/a>\n                        <\/div>\n                                    <\/div>\n            <\/div>\n                    <div class=\"pxl-grid-item col-xl-4 col-lg-4 col-md-6 col-sm-6 col-12 Projects\">\n                <div class=\"pxl-item--inner\">\n                                            <div class=\"pxl-item--image\">\n                            <img loading=\"lazy\" decoding=\"async\" width=\"1920\" height=\"1440\" src=\"https:\/\/mk-mykonos.gr\/wp-content\/uploads\/2025\/10\/20230426_195236.webp\" class=\"no-lazyload\" alt=\"PROJECT MK MYKONOS ENGINEERS\" \/>                            <a href=\"https:\/\/mk-mykonos.gr\/wp-content\/uploads\/2025\/10\/20230426_195236.webp\" class=\"show\"><i class=\"fas fa-eye\"><\/i><\/a>\n                        <\/div>\n                                    <\/div>\n            <\/div>\n                    <div class=\"pxl-grid-item col-xl-4 col-lg-4 col-md-6 col-sm-6 col-12 Projects\">\n                <div class=\"pxl-item--inner\">\n                                            <div class=\"pxl-item--image\">\n                            <img loading=\"lazy\" decoding=\"async\" width=\"1920\" height=\"897\" src=\"https:\/\/mk-mykonos.gr\/wp-content\/uploads\/2025\/10\/20231215_170646.webp\" class=\"no-lazyload\" alt=\"PROJECT MK MYKONOS ENGINEERS\" \/>                            <a href=\"https:\/\/mk-mykonos.gr\/wp-content\/uploads\/2025\/10\/20231215_170646.webp\" class=\"show\"><i class=\"fas fa-eye\"><\/i><\/a>\n                        <\/div>\n                                    <\/div>\n            <\/div>\n                    <div class=\"pxl-grid-item col-xl-4 col-lg-4 col-md-6 col-sm-6 col-12 Projects\">\n                <div class=\"pxl-item--inner\">\n                                            <div class=\"pxl-item--image\">\n                            <img loading=\"lazy\" decoding=\"async\" width=\"1920\" height=\"897\" src=\"https:\/\/mk-mykonos.gr\/wp-content\/uploads\/2025\/10\/20240408_105939.webp\" class=\"no-lazyload\" alt=\"PROJECT MK MYKONOS ENGINEERS\" \/>                            <a href=\"https:\/\/mk-mykonos.gr\/wp-content\/uploads\/2025\/10\/20240408_105939.webp\" class=\"show\"><i class=\"fas fa-eye\"><\/i><\/a>\n                        <\/div>\n                                    <\/div>\n            <\/div>\n                    <div class=\"pxl-grid-item col-xl-4 col-lg-4 col-md-6 col-sm-6 col-12 Projects\">\n                <div class=\"pxl-item--inner\">\n                                            <div class=\"pxl-item--image\">\n                            <img loading=\"lazy\" decoding=\"async\" width=\"1920\" height=\"897\" src=\"https:\/\/mk-mykonos.gr\/wp-content\/uploads\/2025\/10\/20240521_141340.webp\" class=\"no-lazyload\" alt=\"PROJECT MK MYKONOS ENGINEERS\" \/>                            <a href=\"https:\/\/mk-mykonos.gr\/wp-content\/uploads\/2025\/10\/20240521_141340.webp\" class=\"show\"><i class=\"fas fa-eye\"><\/i><\/a>\n                        <\/div>\n                                    <\/div>\n            <\/div>\n                    <div class=\"pxl-grid-item col-xl-4 col-lg-4 col-md-6 col-sm-6 col-12 Projects\">\n                <div class=\"pxl-item--inner\">\n                                            <div class=\"pxl-item--image\">\n                            <img loading=\"lazy\" decoding=\"async\" width=\"990\" height=\"660\" src=\"https:\/\/mk-mykonos.gr\/wp-content\/uploads\/2025\/10\/foto_finishedd_1.webp\" class=\"no-lazyload\" alt=\"PROJECT MK MYKONOS ENGINEERS\" \/>                            <a href=\"https:\/\/mk-mykonos.gr\/wp-content\/uploads\/2025\/10\/foto_finishedd_1.webp\" class=\"show\"><i class=\"fas fa-eye\"><\/i><\/a>\n                        <\/div>\n                                    <\/div>\n            <\/div>\n                    <div class=\"pxl-grid-item col-xl-4 col-lg-4 col-md-6 col-sm-6 col-12 Projects\">\n                <div class=\"pxl-item--inner\">\n                                            <div class=\"pxl-item--image\">\n                            <img loading=\"lazy\" decoding=\"async\" width=\"990\" height=\"660\" src=\"https:\/\/mk-mykonos.gr\/wp-content\/uploads\/2025\/10\/foto_finishedd_2.webp\" class=\"no-lazyload\" alt=\"PROJECT MK MYKONOS ENGINEERS\" \/>                            <a href=\"https:\/\/mk-mykonos.gr\/wp-content\/uploads\/2025\/10\/foto_finishedd_2.webp\" class=\"show\"><i class=\"fas fa-eye\"><\/i><\/a>\n                        <\/div>\n                                    <\/div>\n            <\/div>\n                    <div class=\"pxl-grid-item col-xl-4 col-lg-4 col-md-6 col-sm-6 col-12 Projects\">\n                <div class=\"pxl-item--inner\">\n                                            <div class=\"pxl-item--image\">\n                            <img loading=\"lazy\" decoding=\"async\" width=\"990\" height=\"660\" src=\"https:\/\/mk-mykonos.gr\/wp-content\/uploads\/2025\/10\/foto_finishedd_3.webp\" class=\"no-lazyload\" alt=\"PROJECT MK MYKONOS ENGINEERS\" \/>                            <a href=\"https:\/\/mk-mykonos.gr\/wp-content\/uploads\/2025\/10\/foto_finishedd_3.webp\" class=\"show\"><i class=\"fas fa-eye\"><\/i><\/a>\n                        <\/div>\n                                    <\/div>\n            <\/div>\n                    <div class=\"pxl-grid-item col-xl-4 col-lg-4 col-md-6 col-sm-6 col-12 Projects\">\n                <div class=\"pxl-item--inner\">\n                                            <div class=\"pxl-item--image\">\n                            <img loading=\"lazy\" decoding=\"async\" width=\"990\" height=\"660\" src=\"https:\/\/mk-mykonos.gr\/wp-content\/uploads\/2025\/10\/foto_finishedd_6.webp\" class=\"no-lazyload\" alt=\"PROJECT MK MYKONOS ENGINEERS\" \/>                            <a href=\"https:\/\/mk-mykonos.gr\/wp-content\/uploads\/2025\/10\/foto_finishedd_6.webp\" class=\"show\"><i class=\"fas fa-eye\"><\/i><\/a>\n                        <\/div>\n                                    <\/div>\n            <\/div>\n                    <div class=\"pxl-grid-item col-xl-4 col-lg-4 col-md-6 col-sm-6 col-12 Projects\">\n                <div class=\"pxl-item--inner\">\n                                            <div class=\"pxl-item--image\">\n                            <img loading=\"lazy\" decoding=\"async\" width=\"990\" height=\"742\" src=\"https:\/\/mk-mykonos.gr\/wp-content\/uploads\/2025\/10\/foto_finishedd_7.webp\" class=\"no-lazyload\" alt=\"PROJECT MK MYKONOS ENGINEERS\" \/>                            <a href=\"https:\/\/mk-mykonos.gr\/wp-content\/uploads\/2025\/10\/foto_finishedd_7.webp\" class=\"show\"><i class=\"fas fa-eye\"><\/i><\/a>\n                        <\/div>\n                                    <\/div>\n            <\/div>\n                    <div class=\"pxl-grid-item col-xl-4 col-lg-4 col-md-6 col-sm-6 col-12 Projects\">\n                <div class=\"pxl-item--inner\">\n                                            <div class=\"pxl-item--image\">\n                            <img loading=\"lazy\" decoding=\"async\" width=\"990\" height=\"742\" src=\"https:\/\/mk-mykonos.gr\/wp-content\/uploads\/2025\/10\/foto_finishedd_9.webp\" class=\"no-lazyload\" alt=\"PROJECT MK MYKONOS ENGINEERS\" \/>                            <a href=\"https:\/\/mk-mykonos.gr\/wp-content\/uploads\/2025\/10\/foto_finishedd_9.webp\" class=\"show\"><i class=\"fas fa-eye\"><\/i><\/a>\n                        <\/div>\n                                    <\/div>\n            <\/div>\n                    <div class=\"pxl-grid-item col-xl-4 col-lg-4 col-md-6 col-sm-6 col-12 Projects\">\n                <div class=\"pxl-item--inner\">\n                                            <div class=\"pxl-item--image\">\n                            <img loading=\"lazy\" decoding=\"async\" width=\"990\" height=\"660\" src=\"https:\/\/mk-mykonos.gr\/wp-content\/uploads\/2025\/10\/foto_finishedd_10.webp\" class=\"no-lazyload\" alt=\"PROJECT MK MYKONOS ENGINEERS\" \/>                            <a href=\"https:\/\/mk-mykonos.gr\/wp-content\/uploads\/2025\/10\/foto_finishedd_10.webp\" class=\"show\"><i class=\"fas fa-eye\"><\/i><\/a>\n                        <\/div>\n                                    <\/div>\n            <\/div>\n                    <div class=\"pxl-grid-item col-xl-4 col-lg-4 col-md-6 col-sm-6 col-12 Panormos-House\">\n                <div class=\"pxl-item--inner\">\n                                            <div class=\"pxl-item--image\">\n                            <img loading=\"lazy\" decoding=\"async\" width=\"1920\" height=\"1280\" src=\"https:\/\/mk-mykonos.gr\/wp-content\/uploads\/2025\/10\/0Q6A6417_edit-1.webp\" class=\"no-lazyload\" alt=\"PROJECT PANORMOS\" \/>                            <a href=\"https:\/\/mk-mykonos.gr\/wp-content\/uploads\/2025\/10\/0Q6A6417_edit-1.webp\" class=\"show\"><i class=\"fas fa-eye\"><\/i><\/a>\n                        <\/div>\n                                    <\/div>\n            <\/div>\n                    <div class=\"pxl-grid-item col-xl-4 col-lg-4 col-md-6 col-sm-6 col-12 Panormos-House\">\n                <div class=\"pxl-item--inner\">\n                                            <div class=\"pxl-item--image\">\n                            <img loading=\"lazy\" decoding=\"async\" width=\"1920\" height=\"1208\" src=\"https:\/\/mk-mykonos.gr\/wp-content\/uploads\/2025\/10\/0Q6A6489_edit-1.webp\" class=\"no-lazyload\" alt=\"PROJECT PANORMOS\" \/>                            <a href=\"https:\/\/mk-mykonos.gr\/wp-content\/uploads\/2025\/10\/0Q6A6489_edit-1.webp\" class=\"show\"><i class=\"fas fa-eye\"><\/i><\/a>\n                        <\/div>\n                                    <\/div>\n            <\/div>\n                    <div class=\"pxl-grid-item col-xl-4 col-lg-4 col-md-6 col-sm-6 col-12 Panormos-House\">\n                <div class=\"pxl-item--inner\">\n                                            <div class=\"pxl-item--image\">\n                            <img loading=\"lazy\" decoding=\"async\" width=\"1920\" height=\"1280\" src=\"https:\/\/mk-mykonos.gr\/wp-content\/uploads\/2025\/10\/0Q6A6511_edit-1.webp\" class=\"no-lazyload\" alt=\"PROJECT PANORMOS\" \/>                            <a href=\"https:\/\/mk-mykonos.gr\/wp-content\/uploads\/2025\/10\/0Q6A6511_edit-1.webp\" class=\"show\"><i class=\"fas fa-eye\"><\/i><\/a>\n                        <\/div>\n                                    <\/div>\n            <\/div>\n                    <div class=\"pxl-grid-item col-xl-4 col-lg-4 col-md-6 col-sm-6 col-12 Panormos-House\">\n                <div class=\"pxl-item--inner\">\n                                            <div class=\"pxl-item--image\">\n                            <img loading=\"lazy\" decoding=\"async\" width=\"1920\" height=\"1280\" src=\"https:\/\/mk-mykonos.gr\/wp-content\/uploads\/2025\/10\/0Q6A6515_edit-1.webp\" class=\"no-lazyload\" alt=\"PROJECT PANORMOS\" \/>                            <a href=\"https:\/\/mk-mykonos.gr\/wp-content\/uploads\/2025\/10\/0Q6A6515_edit-1.webp\" class=\"show\"><i class=\"fas fa-eye\"><\/i><\/a>\n                        <\/div>\n                                    <\/div>\n            <\/div>\n                    <div class=\"pxl-grid-item col-xl-4 col-lg-4 col-md-6 col-sm-6 col-12 Panormos-House\">\n                <div class=\"pxl-item--inner\">\n                                            <div class=\"pxl-item--image\">\n                            <img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"682\" src=\"https:\/\/mk-mykonos.gr\/wp-content\/uploads\/2025\/10\/0R1A1691-2.webp\" class=\"no-lazyload\" alt=\"PROJECT PANORMOS\" \/>                            <a href=\"https:\/\/mk-mykonos.gr\/wp-content\/uploads\/2025\/10\/0R1A1691-2.webp\" class=\"show\"><i class=\"fas fa-eye\"><\/i><\/a>\n                        <\/div>\n                                    <\/div>\n            <\/div>\n                    <div class=\"pxl-grid-item col-xl-4 col-lg-4 col-md-6 col-sm-6 col-12 Panormos-House\">\n                <div class=\"pxl-item--inner\">\n                                            <div class=\"pxl-item--image\">\n                            <img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"682\" src=\"https:\/\/mk-mykonos.gr\/wp-content\/uploads\/2025\/10\/0R1A1693-2.webp\" class=\"no-lazyload\" alt=\"PROJECT PANORMOS\" \/>                            <a href=\"https:\/\/mk-mykonos.gr\/wp-content\/uploads\/2025\/10\/0R1A1693-2.webp\" class=\"show\"><i class=\"fas fa-eye\"><\/i><\/a>\n                        <\/div>\n                                    <\/div>\n            <\/div>\n                    <div class=\"pxl-grid-item col-xl-4 col-lg-4 col-md-6 col-sm-6 col-12 Panormos-House\">\n                <div class=\"pxl-item--inner\">\n                                            <div class=\"pxl-item--image\">\n                            <img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"683\" src=\"https:\/\/mk-mykonos.gr\/wp-content\/uploads\/2025\/10\/0R1A1709-3.webp\" class=\"no-lazyload\" alt=\"PROJECT PANORMOS\" \/>                            <a href=\"https:\/\/mk-mykonos.gr\/wp-content\/uploads\/2025\/10\/0R1A1709-3.webp\" class=\"show\"><i class=\"fas fa-eye\"><\/i><\/a>\n                        <\/div>\n                                    <\/div>\n            <\/div>\n                    <div class=\"pxl-grid-item col-xl-4 col-lg-4 col-md-6 col-sm-6 col-12 Panormos-House\">\n                <div class=\"pxl-item--inner\">\n                                            <div class=\"pxl-item--image\">\n                            <img loading=\"lazy\" decoding=\"async\" width=\"1920\" height=\"2560\" src=\"https:\/\/mk-mykonos.gr\/wp-content\/uploads\/2025\/10\/3rd-Bedroom-2.webp\" class=\"no-lazyload\" alt=\"PROJECT PANORMOS\" \/>                            <a href=\"https:\/\/mk-mykonos.gr\/wp-content\/uploads\/2025\/10\/3rd-Bedroom-2.webp\" class=\"show\"><i class=\"fas fa-eye\"><\/i><\/a>\n                        <\/div>\n                                    <\/div>\n            <\/div>\n                    <div class=\"pxl-grid-item col-xl-4 col-lg-4 col-md-6 col-sm-6 col-12 Korfos-House\">\n                <div class=\"pxl-item--inner\">\n                                            <div class=\"pxl-item--image\">\n                            <img loading=\"lazy\" decoding=\"async\" width=\"1360\" height=\"2040\" src=\"https:\/\/mk-mykonos.gr\/wp-content\/uploads\/2026\/06\/bathroom.webp\" class=\"no-lazyload\" alt=\"Modern shower with minimalist design\" \/>                            <a href=\"https:\/\/mk-mykonos.gr\/wp-content\/uploads\/2026\/06\/bathroom.webp\" class=\"show\"><i class=\"fas fa-eye\"><\/i><\/a>\n                        <\/div>\n                                    <\/div>\n            <\/div>\n                    <div class=\"pxl-grid-item col-xl-4 col-lg-4 col-md-6 col-sm-6 col-12 Korfos-House\">\n                <div class=\"pxl-item--inner\">\n                                            <div class=\"pxl-item--image\">\n                            <img loading=\"lazy\" decoding=\"async\" width=\"1360\" height=\"2040\" src=\"https:\/\/mk-mykonos.gr\/wp-content\/uploads\/2026\/06\/ceiling.webp\" class=\"no-lazyload\" alt=\"White wooden beamed ceiling with a small ceramic pendant light hanging on a rope cord\" \/>                            <a href=\"https:\/\/mk-mykonos.gr\/wp-content\/uploads\/2026\/06\/ceiling.webp\" class=\"show\"><i class=\"fas fa-eye\"><\/i><\/a>\n                        <\/div>\n                                    <\/div>\n            <\/div>\n                    <div class=\"pxl-grid-item col-xl-4 col-lg-4 col-md-6 col-sm-6 col-12 Korfos-House\">\n                <div class=\"pxl-item--inner\">\n                                            <div class=\"pxl-item--image\">\n                            <img loading=\"lazy\" decoding=\"async\" width=\"1360\" height=\"2040\" src=\"https:\/\/mk-mykonos.gr\/wp-content\/uploads\/2026\/06\/cupboards.webp\" class=\"no-lazyload\" alt=\"Built in white wardrobe with paneled doors, drawers and open shelving in a bedroom closet nook\" \/>                            <a href=\"https:\/\/mk-mykonos.gr\/wp-content\/uploads\/2026\/06\/cupboards.webp\" class=\"show\"><i class=\"fas fa-eye\"><\/i><\/a>\n                        <\/div>\n                                    <\/div>\n            <\/div>\n                    <div class=\"pxl-grid-item col-xl-4 col-lg-4 col-md-6 col-sm-6 col-12 Korfos-House\">\n                <div class=\"pxl-item--inner\">\n                                            <div class=\"pxl-item--image\">\n                            <img loading=\"lazy\" decoding=\"async\" width=\"2040\" height=\"1360\" src=\"https:\/\/mk-mykonos.gr\/wp-content\/uploads\/2026\/06\/diningtable.webp\" class=\"no-lazyload\" alt=\"Minimalist dining area with cushions\" \/>                            <a href=\"https:\/\/mk-mykonos.gr\/wp-content\/uploads\/2026\/06\/diningtable.webp\" class=\"show\"><i class=\"fas fa-eye\"><\/i><\/a>\n                        <\/div>\n                                    <\/div>\n            <\/div>\n                    <div class=\"pxl-grid-item col-xl-4 col-lg-4 col-md-6 col-sm-6 col-12 Korfos-House\">\n                <div class=\"pxl-item--inner\">\n                                            <div class=\"pxl-item--image\">\n                            <img loading=\"lazy\" decoding=\"async\" width=\"2040\" height=\"1360\" src=\"https:\/\/mk-mykonos.gr\/wp-content\/uploads\/2026\/06\/exterior4.webp\" class=\"no-lazyload\" alt=\"Covered patio with wooden beam ceiling, built in bench seating and dining table beside blue shutters\" \/>                            <a href=\"https:\/\/mk-mykonos.gr\/wp-content\/uploads\/2026\/06\/exterior4.webp\" class=\"show\"><i class=\"fas fa-eye\"><\/i><\/a>\n                        <\/div>\n                                    <\/div>\n            <\/div>\n                    <div class=\"pxl-grid-item col-xl-4 col-lg-4 col-md-6 col-sm-6 col-12 Korfos-House\">\n                <div class=\"pxl-item--inner\">\n                                            <div class=\"pxl-item--image\">\n                            <img loading=\"lazy\" decoding=\"async\" width=\"2040\" height=\"1360\" src=\"https:\/\/mk-mykonos.gr\/wp-content\/uploads\/2026\/06\/kitchen3.webp\" class=\"no-lazyload\" alt=\"Modern kitchen with stainless steel appliances\" \/>                            <a href=\"https:\/\/mk-mykonos.gr\/wp-content\/uploads\/2026\/06\/kitchen3.webp\" class=\"show\"><i class=\"fas fa-eye\"><\/i><\/a>\n                        <\/div>\n                                    <\/div>\n            <\/div>\n                    <div class=\"pxl-grid-item col-xl-4 col-lg-4 col-md-6 col-sm-6 col-12 Korfos-House\">\n                <div class=\"pxl-item--inner\">\n                                            <div class=\"pxl-item--image\">\n                            <img loading=\"lazy\" decoding=\"async\" width=\"2040\" height=\"1360\" src=\"https:\/\/mk-mykonos.gr\/wp-content\/uploads\/2026\/06\/livingroom.webp\" class=\"no-lazyload\" alt=\"living room project interior house in korfos mykonos\" \/>                            <a href=\"https:\/\/mk-mykonos.gr\/wp-content\/uploads\/2026\/06\/livingroom.webp\" class=\"show\"><i class=\"fas fa-eye\"><\/i><\/a>\n                        <\/div>\n                                    <\/div>\n            <\/div>\n                    <div class=\"pxl-grid-item col-xl-4 col-lg-4 col-md-6 col-sm-6 col-12 Villa-in-Mykonos\">\n                <div class=\"pxl-item--inner\">\n                                            <div class=\"pxl-item--image\">\n                            <img loading=\"lazy\" decoding=\"async\" width=\"2040\" height=\"1359\" src=\"https:\/\/mk-mykonos.gr\/wp-content\/uploads\/2026\/06\/aerialview1.webp\" class=\"no-lazyload\" alt=\"Illuminated white villa with glowing pool overlooking a Greek island town at night\" \/>                            <a href=\"https:\/\/mk-mykonos.gr\/wp-content\/uploads\/2026\/06\/aerialview1.webp\" class=\"show\"><i class=\"fas fa-eye\"><\/i><\/a>\n                        <\/div>\n                                    <\/div>\n            <\/div>\n                    <div class=\"pxl-grid-item col-xl-4 col-lg-4 col-md-6 col-sm-6 col-12 Villa-in-Mykonos\">\n                <div class=\"pxl-item--inner\">\n                                            <div class=\"pxl-item--image\">\n                            <img loading=\"lazy\" decoding=\"async\" width=\"1360\" height=\"2040\" src=\"https:\/\/mk-mykonos.gr\/wp-content\/uploads\/2026\/06\/bathroom-1.webp\" class=\"no-lazyload\" alt=\"Modern bathroom with glass shower enclosure and freestanding pink oval sink on black frame\" \/>                            <a href=\"https:\/\/mk-mykonos.gr\/wp-content\/uploads\/2026\/06\/bathroom-1.webp\" class=\"show\"><i class=\"fas fa-eye\"><\/i><\/a>\n                        <\/div>\n                                    <\/div>\n            <\/div>\n                    <div class=\"pxl-grid-item col-xl-4 col-lg-4 col-md-6 col-sm-6 col-12 Villa-in-Mykonos\">\n                <div class=\"pxl-item--inner\">\n                                            <div class=\"pxl-item--image\">\n                            <img loading=\"lazy\" decoding=\"async\" width=\"2040\" height=\"1360\" src=\"https:\/\/mk-mykonos.gr\/wp-content\/uploads\/2026\/06\/bathroom4.webp\" class=\"no-lazyload\" alt=\"Modern bathroom with wooden vanity, gold fixtures, and view into toilet area with mosaic tile wall\" \/>                            <a href=\"https:\/\/mk-mykonos.gr\/wp-content\/uploads\/2026\/06\/bathroom4.webp\" class=\"show\"><i class=\"fas fa-eye\"><\/i><\/a>\n                        <\/div>\n                                    <\/div>\n            <\/div>\n                    <div class=\"pxl-grid-item col-xl-4 col-lg-4 col-md-6 col-sm-6 col-12 Villa-in-Mykonos\">\n                <div class=\"pxl-item--inner\">\n                                            <div class=\"pxl-item--image\">\n                            <img loading=\"lazy\" decoding=\"async\" width=\"2040\" height=\"1360\" src=\"https:\/\/mk-mykonos.gr\/wp-content\/uploads\/2026\/06\/entrance1.webp\" class=\"no-lazyload\" alt=\"interior design of property in mykonos\" \/>                            <a href=\"https:\/\/mk-mykonos.gr\/wp-content\/uploads\/2026\/06\/entrance1.webp\" class=\"show\"><i class=\"fas fa-eye\"><\/i><\/a>\n                        <\/div>\n                                    <\/div>\n            <\/div>\n                    <div class=\"pxl-grid-item col-xl-4 col-lg-4 col-md-6 col-sm-6 col-12 Villa-in-Mykonos\">\n                <div class=\"pxl-item--inner\">\n                                            <div class=\"pxl-item--image\">\n                            <img loading=\"lazy\" decoding=\"async\" width=\"2040\" height=\"1360\" src=\"https:\/\/mk-mykonos.gr\/wp-content\/uploads\/2026\/06\/exteriorareas.webp\" class=\"no-lazyload\" alt=\"Whitewashed Mediterranean villa with stone terraced garden pathways and lush landscaping\" \/>                            <a href=\"https:\/\/mk-mykonos.gr\/wp-content\/uploads\/2026\/06\/exteriorareas.webp\" class=\"show\"><i class=\"fas fa-eye\"><\/i><\/a>\n                        <\/div>\n                                    <\/div>\n            <\/div>\n                    <div class=\"pxl-grid-item col-xl-4 col-lg-4 col-md-6 col-sm-6 col-12 Villa-in-Mykonos\">\n                <div class=\"pxl-item--inner\">\n                                            <div class=\"pxl-item--image\">\n                            <img loading=\"lazy\" decoding=\"async\" width=\"2040\" height=\"1360\" src=\"https:\/\/mk-mykonos.gr\/wp-content\/uploads\/2026\/06\/exteriorentrance.webp\" class=\"no-lazyload\" alt=\"entrance of villa house in mykonos\" \/>                            <a href=\"https:\/\/mk-mykonos.gr\/wp-content\/uploads\/2026\/06\/exteriorentrance.webp\" class=\"show\"><i class=\"fas fa-eye\"><\/i><\/a>\n                        <\/div>\n                                    <\/div>\n            <\/div>\n                    <div class=\"pxl-grid-item col-xl-4 col-lg-4 col-md-6 col-sm-6 col-12 Villa-in-Mykonos\">\n                <div class=\"pxl-item--inner\">\n                                            <div class=\"pxl-item--image\">\n                            <img loading=\"lazy\" decoding=\"async\" width=\"2040\" height=\"1360\" src=\"https:\/\/mk-mykonos.gr\/wp-content\/uploads\/2026\/06\/interiorandexteriorsunset.webp\" class=\"no-lazyload\" alt=\"interior of property in mykonos\" \/>                            <a href=\"https:\/\/mk-mykonos.gr\/wp-content\/uploads\/2026\/06\/interiorandexteriorsunset.webp\" class=\"show\"><i class=\"fas fa-eye\"><\/i><\/a>\n                        <\/div>\n                                    <\/div>\n            <\/div>\n                    <div class=\"pxl-grid-item col-xl-4 col-lg-4 col-md-6 col-sm-6 col-12 Villa-in-Mykonos\">\n                <div class=\"pxl-item--inner\">\n                                            <div class=\"pxl-item--image\">\n                            <img loading=\"lazy\" decoding=\"async\" width=\"2040\" height=\"1360\" src=\"https:\/\/mk-mykonos.gr\/wp-content\/uploads\/2026\/06\/interiorlivingroom1.webp\" class=\"no-lazyload\" alt=\"Open plan living and dining room with wooden table, stone accent wall, and ocean view through floor to ceiling windows\" \/>                            <a href=\"https:\/\/mk-mykonos.gr\/wp-content\/uploads\/2026\/06\/interiorlivingroom1.webp\" class=\"show\"><i class=\"fas fa-eye\"><\/i><\/a>\n                        <\/div>\n                                    <\/div>\n            <\/div>\n                    <div class=\"pxl-grid-item col-xl-4 col-lg-4 col-md-6 col-sm-6 col-12 Villa-in-Mykonos\">\n                <div class=\"pxl-item--inner\">\n                                            <div class=\"pxl-item--image\">\n                            <img loading=\"lazy\" decoding=\"async\" width=\"2040\" height=\"1360\" src=\"https:\/\/mk-mykonos.gr\/wp-content\/uploads\/2026\/06\/rooms7.webp\" class=\"no-lazyload\" alt=\"bedroom of property in mykonos\" \/>                            <a href=\"https:\/\/mk-mykonos.gr\/wp-content\/uploads\/2026\/06\/rooms7.webp\" class=\"show\"><i class=\"fas fa-eye\"><\/i><\/a>\n                        <\/div>\n                                    <\/div>\n            <\/div>\n                    <div class=\"pxl-grid-item col-xl-4 col-lg-4 col-md-6 col-sm-6 col-12 Villa-in-Mykonos\">\n                <div class=\"pxl-item--inner\">\n                                            <div class=\"pxl-item--image\">\n                            <img loading=\"lazy\" decoding=\"async\" width=\"2040\" height=\"1360\" src=\"https:\/\/mk-mykonos.gr\/wp-content\/uploads\/2026\/06\/swimmingpool.webp\" class=\"no-lazyload\" alt=\"swimming pool of property in mykonos\" \/>                            <a href=\"https:\/\/mk-mykonos.gr\/wp-content\/uploads\/2026\/06\/swimmingpool.webp\" class=\"show\"><i class=\"fas fa-eye\"><\/i><\/a>\n                        <\/div>\n                                    <\/div>\n            <\/div>\n                    <div class=\"pxl-grid-item col-xl-4 col-lg-4 col-md-6 col-sm-6 col-12 54-Bar\">\n                <div class=\"pxl-item--inner\">\n                                            <div class=\"pxl-item--image\">\n                            <img loading=\"lazy\" decoding=\"async\" width=\"2040\" height=\"1360\" src=\"https:\/\/mk-mykonos.gr\/wp-content\/uploads\/2026\/06\/@54-1-2430x1620-1.webp\" class=\"no-lazyload\" alt=\"54 mykonos\" \/>                            <a href=\"https:\/\/mk-mykonos.gr\/wp-content\/uploads\/2026\/06\/@54-1-2430x1620-1.webp\" class=\"show\"><i class=\"fas fa-eye\"><\/i><\/a>\n                        <\/div>\n                                    <\/div>\n            <\/div>\n                    <div class=\"pxl-grid-item col-xl-4 col-lg-4 col-md-6 col-sm-6 col-12 54-Bar\">\n                <div class=\"pxl-item--inner\">\n                                            <div class=\"pxl-item--image\">\n                            <img loading=\"lazy\" decoding=\"async\" width=\"2040\" height=\"1360\" src=\"https:\/\/mk-mykonos.gr\/wp-content\/uploads\/2026\/06\/@54-3-2430x1620-1.webp\" class=\"no-lazyload\" alt=\"54 club mykonos\" \/>                            <a href=\"https:\/\/mk-mykonos.gr\/wp-content\/uploads\/2026\/06\/@54-3-2430x1620-1.webp\" class=\"show\"><i class=\"fas fa-eye\"><\/i><\/a>\n                        <\/div>\n                                    <\/div>\n            <\/div>\n                    <div class=\"pxl-grid-item col-xl-4 col-lg-4 col-md-6 col-sm-6 col-12 54-Bar\">\n                <div class=\"pxl-item--inner\">\n                                            <div class=\"pxl-item--image\">\n                            <img loading=\"lazy\" decoding=\"async\" width=\"2040\" height=\"1293\" src=\"https:\/\/mk-mykonos.gr\/wp-content\/uploads\/2026\/06\/@54-8-2556x1620-1.webp\" class=\"no-lazyload\" alt=\"Illuminated bar counter with rows of liquor bottles under purple and blue neon lighting in a nightclub\" \/>                            <a href=\"https:\/\/mk-mykonos.gr\/wp-content\/uploads\/2026\/06\/@54-8-2556x1620-1.webp\" class=\"show\"><i class=\"fas fa-eye\"><\/i><\/a>\n                        <\/div>\n                                    <\/div>\n            <\/div>\n                    <div class=\"pxl-grid-item col-xl-4 col-lg-4 col-md-6 col-sm-6 col-12 54-Bar\">\n                <div class=\"pxl-item--inner\">\n                                            <div class=\"pxl-item--image\">\n                            <img loading=\"lazy\" decoding=\"async\" width=\"2040\" height=\"1359\" src=\"https:\/\/mk-mykonos.gr\/wp-content\/uploads\/2026\/06\/@54-11-2431x1620-1.webp\" class=\"no-lazyload\" alt=\"@54 bar in mykonos\" \/>                            <a href=\"https:\/\/mk-mykonos.gr\/wp-content\/uploads\/2026\/06\/@54-11-2431x1620-1.webp\" class=\"show\"><i class=\"fas fa-eye\"><\/i><\/a>\n                        <\/div>\n                                    <\/div>\n            <\/div>\n                    <div class=\"pxl-grid-item col-xl-4 col-lg-4 col-md-6 col-sm-6 col-12 Bowling\">\n                <div class=\"pxl-item--inner\">\n                                            <div class=\"pxl-item--image\">\n                            <img loading=\"lazy\" decoding=\"async\" width=\"1920\" height=\"1080\" src=\"https:\/\/mk-mykonos.gr\/wp-content\/uploads\/2026\/06\/bowling02.webp\" class=\"no-lazyload\" alt=\"bowling center in mykonos\" \/>                            <a href=\"https:\/\/mk-mykonos.gr\/wp-content\/uploads\/2026\/06\/bowling02.webp\" class=\"show\"><i class=\"fas fa-eye\"><\/i><\/a>\n                        <\/div>\n                                    <\/div>\n            <\/div>\n                    <div class=\"pxl-grid-item col-xl-4 col-lg-4 col-md-6 col-sm-6 col-12 Bowling\">\n                <div class=\"pxl-item--inner\">\n                                            <div class=\"pxl-item--image\">\n                            <img loading=\"lazy\" decoding=\"async\" width=\"1920\" height=\"1080\" src=\"https:\/\/mk-mykonos.gr\/wp-content\/uploads\/2026\/06\/bowling03.webp\" class=\"no-lazyload\" alt=\"People gather at wooden tables in a modern bowling alley lounge with green stools and pins visible down the lane\" \/>                            <a href=\"https:\/\/mk-mykonos.gr\/wp-content\/uploads\/2026\/06\/bowling03.webp\" class=\"show\"><i class=\"fas fa-eye\"><\/i><\/a>\n                        <\/div>\n                                    <\/div>\n            <\/div>\n                    <div class=\"pxl-grid-item col-xl-4 col-lg-4 col-md-6 col-sm-6 col-12 Bowling\">\n                <div class=\"pxl-item--inner\">\n                                            <div class=\"pxl-item--image\">\n                            <img loading=\"lazy\" decoding=\"async\" width=\"1920\" height=\"1080\" src=\"https:\/\/mk-mykonos.gr\/wp-content\/uploads\/2026\/06\/bowling05.webp\" class=\"no-lazyload\" alt=\"bowling in mykons\" \/>                            <a href=\"https:\/\/mk-mykonos.gr\/wp-content\/uploads\/2026\/06\/bowling05.webp\" class=\"show\"><i class=\"fas fa-eye\"><\/i><\/a>\n                        <\/div>\n                                    <\/div>\n            <\/div>\n                    <div class=\"pxl-grid-item col-xl-4 col-lg-4 col-md-6 col-sm-6 col-12 Bowling\">\n                <div class=\"pxl-item--inner\">\n                                            <div class=\"pxl-item--image\">\n                            <img loading=\"lazy\" decoding=\"async\" width=\"1920\" height=\"1080\" src=\"https:\/\/mk-mykonos.gr\/wp-content\/uploads\/2026\/06\/bowling08.webp\" class=\"no-lazyload\" alt=\"Colorful uplighting illuminates stone columns above a lower level bar area with people at tables\" \/>                            <a href=\"https:\/\/mk-mykonos.gr\/wp-content\/uploads\/2026\/06\/bowling08.webp\" class=\"show\"><i class=\"fas fa-eye\"><\/i><\/a>\n                        <\/div>\n                                    <\/div>\n            <\/div>\n                    <div class=\"pxl-grid-item col-xl-4 col-lg-4 col-md-6 col-sm-6 col-12 Palladium\">\n                <div class=\"pxl-item--inner\">\n                                            <div class=\"pxl-item--image\">\n                            <img loading=\"lazy\" decoding=\"async\" width=\"1920\" height=\"1080\" src=\"https:\/\/mk-mykonos.gr\/wp-content\/uploads\/2026\/06\/Palladium-Pool01.webp\" class=\"no-lazyload\" alt=\"Twilight view of a resort pool with a spiral sculpture fountain and white lounge chairs\" \/>                            <a href=\"https:\/\/mk-mykonos.gr\/wp-content\/uploads\/2026\/06\/Palladium-Pool01.webp\" class=\"show\"><i class=\"fas fa-eye\"><\/i><\/a>\n                        <\/div>\n                                    <\/div>\n            <\/div>\n                    <div class=\"pxl-grid-item col-xl-4 col-lg-4 col-md-6 col-sm-6 col-12 Palladium\">\n                <div class=\"pxl-item--inner\">\n                                            <div class=\"pxl-item--image\">\n                            <img loading=\"lazy\" decoding=\"async\" width=\"1920\" height=\"1080\" src=\"https:\/\/mk-mykonos.gr\/wp-content\/uploads\/2026\/06\/Palladium-Pool02.webp\" class=\"no-lazyload\" alt=\"Luxury resort pool and terrace with palm trees illuminated at twilight overlooking the Aegean Sea\" \/>                            <a href=\"https:\/\/mk-mykonos.gr\/wp-content\/uploads\/2026\/06\/Palladium-Pool02.webp\" class=\"show\"><i class=\"fas fa-eye\"><\/i><\/a>\n                        <\/div>\n                                    <\/div>\n            <\/div>\n                    <div class=\"pxl-grid-item col-xl-4 col-lg-4 col-md-6 col-sm-6 col-12 Palladium\">\n                <div class=\"pxl-item--inner\">\n                                            <div class=\"pxl-item--image\">\n                            <img loading=\"lazy\" decoding=\"async\" width=\"1920\" height=\"1080\" src=\"https:\/\/mk-mykonos.gr\/wp-content\/uploads\/2026\/06\/Palladium-Pool11.webp\" class=\"no-lazyload\" alt=\"Bright blue swimming pool with white platform sculpture at a Mediterranean style resort\" \/>                            <a href=\"https:\/\/mk-mykonos.gr\/wp-content\/uploads\/2026\/06\/Palladium-Pool11.webp\" class=\"show\"><i class=\"fas fa-eye\"><\/i><\/a>\n                        <\/div>\n                                    <\/div>\n            <\/div>\n                    <div class=\"pxl-grid-item col-xl-4 col-lg-4 col-md-6 col-sm-6 col-12 Palladium\">\n                <div class=\"pxl-item--inner\">\n                                            <div class=\"pxl-item--image\">\n                            <img loading=\"lazy\" decoding=\"async\" width=\"1920\" height=\"1080\" src=\"https:\/\/mk-mykonos.gr\/wp-content\/uploads\/2026\/06\/Palladium-Pool09.webp\" class=\"no-lazyload\" alt=\"palladium\" \/>                            <a href=\"https:\/\/mk-mykonos.gr\/wp-content\/uploads\/2026\/06\/Palladium-Pool09.webp\" class=\"show\"><i class=\"fas fa-eye\"><\/i><\/a>\n                        <\/div>\n                                    <\/div>\n            <\/div>\n                    <div class=\"pxl-grid-item col-xl-4 col-lg-4 col-md-6 col-sm-6 col-12 Palladium\">\n                <div class=\"pxl-item--inner\">\n                                            <div class=\"pxl-item--image\">\n                            <img loading=\"lazy\" decoding=\"async\" width=\"737\" height=\"1080\" src=\"https:\/\/mk-mykonos.gr\/wp-content\/uploads\/2026\/06\/Palladium-Pool07.webp\" class=\"no-lazyload\" alt=\"Illuminated resort poolside lounge with palm trees glowing at dusk against a deep blue sky\" \/>                            <a href=\"https:\/\/mk-mykonos.gr\/wp-content\/uploads\/2026\/06\/Palladium-Pool07.webp\" class=\"show\"><i class=\"fas fa-eye\"><\/i><\/a>\n                        <\/div>\n                                    <\/div>\n            <\/div>\n                    <div class=\"pxl-grid-item col-xl-4 col-lg-4 col-md-6 col-sm-6 col-12 Saint-John-Hotel\">\n                <div class=\"pxl-item--inner\">\n                                            <div class=\"pxl-item--image\">\n                            <img loading=\"lazy\" decoding=\"async\" width=\"1920\" height=\"1080\" src=\"https:\/\/mk-mykonos.gr\/wp-content\/uploads\/2026\/06\/saint-john-hotel-mykonos01.webp\" class=\"no-lazyload\" alt=\"saint john hotel\" \/>                            <a href=\"https:\/\/mk-mykonos.gr\/wp-content\/uploads\/2026\/06\/saint-john-hotel-mykonos01.webp\" class=\"show\"><i class=\"fas fa-eye\"><\/i><\/a>\n                        <\/div>\n                                    <\/div>\n            <\/div>\n                    <div class=\"pxl-grid-item col-xl-4 col-lg-4 col-md-6 col-sm-6 col-12 Saint-John-Hotel\">\n                <div class=\"pxl-item--inner\">\n                                            <div class=\"pxl-item--image\">\n                            <img loading=\"lazy\" decoding=\"async\" width=\"1920\" height=\"1080\" src=\"https:\/\/mk-mykonos.gr\/wp-content\/uploads\/2026\/06\/saint-john-hotel-mykonos03.webp\" class=\"no-lazyload\" alt=\"Private terrace with infinity plunge pool and lounge chairs overlooking the sea\" \/>                            <a href=\"https:\/\/mk-mykonos.gr\/wp-content\/uploads\/2026\/06\/saint-john-hotel-mykonos03.webp\" class=\"show\"><i class=\"fas fa-eye\"><\/i><\/a>\n                        <\/div>\n                                    <\/div>\n            <\/div>\n                    <div class=\"pxl-grid-item col-xl-4 col-lg-4 col-md-6 col-sm-6 col-12 Saint-John-Hotel\">\n                <div class=\"pxl-item--inner\">\n                                            <div class=\"pxl-item--image\">\n                            <img loading=\"lazy\" decoding=\"async\" width=\"1920\" height=\"1080\" src=\"https:\/\/mk-mykonos.gr\/wp-content\/uploads\/2026\/06\/saint-john-hotel-mykonos06.webp\" class=\"no-lazyload\" alt=\"Covered terrace with white lounge chairs and round table overlooking Mykonos style whitewashed buildings\" \/>                            <a href=\"https:\/\/mk-mykonos.gr\/wp-content\/uploads\/2026\/06\/saint-john-hotel-mykonos06.webp\" class=\"show\"><i class=\"fas fa-eye\"><\/i><\/a>\n                        <\/div>\n                                    <\/div>\n            <\/div>\n                    <div class=\"pxl-grid-item col-xl-4 col-lg-4 col-md-6 col-sm-6 col-12 Saint-John-Hotel\">\n                <div class=\"pxl-item--inner\">\n                                            <div class=\"pxl-item--image\">\n                            <img loading=\"lazy\" decoding=\"async\" width=\"1920\" height=\"1080\" src=\"https:\/\/mk-mykonos.gr\/wp-content\/uploads\/2026\/06\/saint-john-hotel-mykonos07.webp\" class=\"no-lazyload\" alt=\"saint john mykonos\" \/>                            <a href=\"https:\/\/mk-mykonos.gr\/wp-content\/uploads\/2026\/06\/saint-john-hotel-mykonos07.webp\" class=\"show\"><i class=\"fas fa-eye\"><\/i><\/a>\n                        <\/div>\n                                    <\/div>\n            <\/div>\n                    <div class=\"pxl-grid-item col-xl-4 col-lg-4 col-md-6 col-sm-6 col-12 Saint-John-Hotel\">\n                <div class=\"pxl-item--inner\">\n                                            <div class=\"pxl-item--image\">\n                            <img loading=\"lazy\" decoding=\"async\" width=\"1920\" height=\"1080\" src=\"https:\/\/mk-mykonos.gr\/wp-content\/uploads\/2026\/06\/saint-john-hotel-mykonos10.webp\" class=\"no-lazyload\" alt=\"Modern bathroom with decorative glass partition opens to a bedroom and pool view\" \/>                            <a href=\"https:\/\/mk-mykonos.gr\/wp-content\/uploads\/2026\/06\/saint-john-hotel-mykonos10.webp\" class=\"show\"><i class=\"fas fa-eye\"><\/i><\/a>\n                        <\/div>\n                                    <\/div>\n            <\/div>\n                    <div class=\"pxl-grid-item col-xl-4 col-lg-4 col-md-6 col-sm-6 col-12 Vicolo\">\n                <div class=\"pxl-item--inner\">\n                                            <div class=\"pxl-item--image\">\n                            <img loading=\"lazy\" decoding=\"async\" width=\"809\" height=\"1080\" src=\"https:\/\/mk-mykonos.gr\/wp-content\/uploads\/2026\/06\/vicolo-bar-Mykonos-01.webp\" class=\"no-lazyload\" alt=\"Person seated on bar stool in narrow corridor with stone-patterned floor and warm red ambient lighting\" \/>                            <a href=\"https:\/\/mk-mykonos.gr\/wp-content\/uploads\/2026\/06\/vicolo-bar-Mykonos-01.webp\" class=\"show\"><i class=\"fas fa-eye\"><\/i><\/a>\n                        <\/div>\n                                    <\/div>\n            <\/div>\n                    <div class=\"pxl-grid-item col-xl-4 col-lg-4 col-md-6 col-sm-6 col-12 Vicolo\">\n                <div class=\"pxl-item--inner\">\n                                            <div class=\"pxl-item--image\">\n                            <img loading=\"lazy\" decoding=\"async\" width=\"1920\" height=\"1080\" src=\"https:\/\/mk-mykonos.gr\/wp-content\/uploads\/2026\/06\/vicolo-bar-Mykonos-04.webp\" class=\"no-lazyload\" alt=\"vicolo bar\" \/>                            <a href=\"https:\/\/mk-mykonos.gr\/wp-content\/uploads\/2026\/06\/vicolo-bar-Mykonos-04.webp\" class=\"show\"><i class=\"fas fa-eye\"><\/i><\/a>\n                        <\/div>\n                                    <\/div>\n            <\/div>\n                    <div class=\"pxl-grid-item col-xl-4 col-lg-4 col-md-6 col-sm-6 col-12 Vicolo\">\n                <div class=\"pxl-item--inner\">\n                                            <div class=\"pxl-item--image\">\n                            <img loading=\"lazy\" decoding=\"async\" width=\"1920\" height=\"1080\" src=\"https:\/\/mk-mykonos.gr\/wp-content\/uploads\/2026\/06\/vicolo-bar-Mykonos-05.webp\" class=\"no-lazyload\" alt=\"vicolo bar mykonos\" \/>                            <a href=\"https:\/\/mk-mykonos.gr\/wp-content\/uploads\/2026\/06\/vicolo-bar-Mykonos-05.webp\" class=\"show\"><i class=\"fas fa-eye\"><\/i><\/a>\n                        <\/div>\n                                    <\/div>\n            <\/div>\n                    <div class=\"pxl-grid-item col-xl-4 col-lg-4 col-md-6 col-sm-6 col-12 Vicolo\">\n                <div class=\"pxl-item--inner\">\n                                            <div class=\"pxl-item--image\">\n                            <img loading=\"lazy\" decoding=\"async\" width=\"1920\" height=\"1080\" src=\"https:\/\/mk-mykonos.gr\/wp-content\/uploads\/2026\/06\/vicolo-bar-Mykonos-07.webp\" class=\"no-lazyload\" alt=\"Greek island style cafe interior with blue shuttered doors, white round tables and colorful striped cushions\" \/>                            <a href=\"https:\/\/mk-mykonos.gr\/wp-content\/uploads\/2026\/06\/vicolo-bar-Mykonos-07.webp\" class=\"show\"><i class=\"fas fa-eye\"><\/i><\/a>\n                        <\/div>\n                                    <\/div>\n            <\/div>\n                    <div class=\"pxl-grid-item col-xl-4 col-lg-4 col-md-6 col-sm-6 col-12 Vicolo\">\n                <div class=\"pxl-item--inner\">\n                                            <div class=\"pxl-item--image\">\n                            <img loading=\"lazy\" decoding=\"async\" width=\"1920\" height=\"1080\" src=\"https:\/\/mk-mykonos.gr\/wp-content\/uploads\/2026\/06\/vicolo-bar-Mykonos-06.webp\" class=\"no-lazyload\" alt=\"vicolo project bar\" \/>                            <a href=\"https:\/\/mk-mykonos.gr\/wp-content\/uploads\/2026\/06\/vicolo-bar-Mykonos-06.webp\" class=\"show\"><i class=\"fas fa-eye\"><\/i><\/a>\n                        <\/div>\n                                    <\/div>\n            <\/div>\n                    <div class=\"pxl-grid-item col-xl-4 col-lg-4 col-md-6 col-sm-6 col-12 Vicolo\">\n                <div class=\"pxl-item--inner\">\n                                            <div class=\"pxl-item--image\">\n                            <img loading=\"lazy\" decoding=\"async\" width=\"1200\" height=\"675\" src=\"https:\/\/mk-mykonos.gr\/wp-content\/uploads\/2026\/06\/vicolo-bar-Mykonos-08-1200x675-1.webp\" class=\"no-lazyload\" alt=\"vicolo bar mykonos\" \/>                            <a href=\"https:\/\/mk-mykonos.gr\/wp-content\/uploads\/2026\/06\/vicolo-bar-Mykonos-08-1200x675-1.webp\" class=\"show\"><i class=\"fas fa-eye\"><\/i><\/a>\n                        <\/div>\n                                    <\/div>\n            <\/div>\n            <\/div>\n<\/div>\n<div id=\"popup\">\n    <div class=\"wrap-popup\">\n        <span id=\"close\">\u00d7<\/span>\n        <span id=\"prev\" class=\"arrow\">\u276e<\/span>\n        <img decoding=\"async\" id=\"popup-img\" src=\"\" alt=\"Popup Image\">\n        <span id=\"next\" class=\"arrow\">\u276f<\/span>\n    <\/div>\n<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t            <\/div>\r\n        <\/div>\r\n        \t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<\/div>","protected":false},"excerpt":{"rendered":"<p>Explore Our Work Our Projects Our gallery showcases the dedication, creativity, and craftsmanship we bring to every project. Home All Projects Panormos House Korfos House Villa in Mykonos 54 Bar Bowling Palladium Saint John Hotel Vicolo \u00d7 \u276e \u276f<\/p>","protected":false},"author":7,"featured_media":0,"parent":0,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"","meta":{"footnotes":""},"class_list":["post-33","page","type-page","status-publish","hentry"],"_links":{"self":[{"href":"https:\/\/mk-mykonos.gr\/el\/wp-json\/wp\/v2\/pages\/33","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/mk-mykonos.gr\/el\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/mk-mykonos.gr\/el\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/mk-mykonos.gr\/el\/wp-json\/wp\/v2\/users\/7"}],"replies":[{"embeddable":true,"href":"https:\/\/mk-mykonos.gr\/el\/wp-json\/wp\/v2\/comments?post=33"}],"version-history":[{"count":0,"href":"https:\/\/mk-mykonos.gr\/el\/wp-json\/wp\/v2\/pages\/33\/revisions"}],"wp:attachment":[{"href":"https:\/\/mk-mykonos.gr\/el\/wp-json\/wp\/v2\/media?parent=33"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}